{"id":9283,"date":"2023-05-04T11:52:23","date_gmt":"2023-05-04T09:52:23","guid":{"rendered":"https:\/\/flamencomalaga.com\/serranas-quelle-est-cette-chanson-flamenco\/"},"modified":"2025-06-26T16:58:10","modified_gmt":"2025-06-26T14:58:10","slug":"serranas-quelle-est-cette-chanson-flamenco","status":"publish","type":"post","link":"https:\/\/flamencomalaga.com\/fr\/blog\/serranas-quelle-est-cette-chanson-flamenco\/","title":{"rendered":"Serranas : Quelle est cette chanson flamenco ?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Les <\/span><b>serranas del flamenco<\/b><span style=\"font-weight: 400;\">  sont un type de cante \u00e0 l&rsquo;atmosph\u00e8re paysanne, dont les th\u00e8mes font principalement r\u00e9f\u00e9rence \u00e0 la sierra, les protagonistes \u00e9tant des bergers, des contrebandiers, des bandits et des muletiers. D&rsquo;o\u00f9 son nom, qui fait r\u00e9f\u00e9rence \u00e0 la sierra andalouse, et plus pr\u00e9cis\u00e9ment \u00e0 la Serran\u00eda de Ronda. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Un cante qui, <\/span><b>au milieu du 19\u00e8me si\u00e8cle, jouissait d&rsquo;une grande popularit\u00e9<\/b><span style=\"font-weight: 400;\">Il \u00e9tait tr\u00e8s pr\u00e9sent dans le r\u00e9pertoire des cantaores qui se produisaient dans les tablaos des th\u00e9\u00e2tres. De nos jours, cependant, il est de moins en moins utilis\u00e9 en raison des restrictions impos\u00e9es par sa structure m\u00e9lodique. <\/span><\/p>\n<h2><b>Qu&rsquo;est-ce que le flamenco serrana ?<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">La <\/span><b>serrana du flamenco<\/b><span style=\"font-weight: 400;\">  est un style flamenco avec une copla de quatre lignes paires rim\u00e9es, dont la premi\u00e8re et la troisi\u00e8me ont sept syllabes, et la deuxi\u00e8me et la quatri\u00e8me cinq syllabes. Il est compl\u00e9t\u00e9 par un tercet dans lequel les lignes impaires riment, tandis que la deuxi\u00e8me ligne est libre. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il est d\u00e9fini comme un <\/span><b>chant m\u00e9lodieux<\/b><span style=\"font-weight: 400;\">courageux <\/span><b>solennel et de longues phrases qui<\/b><span style=\"font-weight: 400;\">  exige de la part de ses chanteurs de grandes capacit\u00e9s d&rsquo;interpr\u00e9tation. En outre, une voix harmonieuse est n\u00e9cessaire pour pouvoir temp\u00e9rer les vers et les allonger autant que n\u00e9cessaire. <\/span><\/p>\n<h2><b>Quelle est l&rsquo;origine du chant flamenco de la serrana ?<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Le <\/span><b>cante flamenco por serranas<\/b><span style=\"font-weight: 400;\"> semble provenir d&rsquo;une <\/span><b>chanson folklorique andalouse,<\/b><span style=\"font-weight: 400;\"> probablement d\u00e9pourvue de comp\u00e1s, qui <\/span><b>qui a \u00e9t\u00e9 flamencis\u00e9e au milieu du 19e si\u00e8cle.<\/b><span style=\"font-weight: 400;\">. Cependant, au XVIe si\u00e8cle, il existait d\u00e9j\u00e0 un chant lyrique connu sous le nom de serranilla, dont la composition litt\u00e9raire semble tr\u00e8s proche de celle de la serrana. La plupart des auteurs s&rsquo;accordent \u00e0 dire que la m\u00e9lodie contient des airs de ca\u00f1a, de seguiriya et, surtout, de liviana. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Certains auteurs consid\u00e8rent que ce genre est \u00e9troitement li\u00e9 aux contrebandiers gitans qui, au XIXe si\u00e8cle, \u00e9taient connus sous le nom de \u00ab\u00a0serranos\u00a0\u00bb. D&rsquo;autres pensent qu&rsquo;il d\u00e9rive des seguidillas sevillanas et des manchegas, et d&rsquo;autres encore affirment que la liviana, la calesera et la serrana ont \u00e9t\u00e9, \u00e0 un moment donn\u00e9, un seul et m\u00eame genre. Certains auteurs insistent m\u00eame sur le fait qu&rsquo;il s&rsquo;agit d&rsquo;un cante cordouan, mais qu&rsquo;il pourrait \u00eatre originaire de n&rsquo;importe quelle sierra andalouse.  <\/span><\/p>\n<p><span style=\"font-weight: 400;\">En tout cas, ce qui est certain, c&rsquo;est que<\/span><b> Silverio Franconetti<\/b><span style=\"font-weight: 400;\">  est consid\u00e9r\u00e9 comme le premier promoteur des serranas, qui a \u00e9tabli la tendance \u00e0 les chanter, pr\u00e9c\u00e9d\u00e9es par les livianas et termin\u00e9es par les seguiriyas de cambio. Mais il y a aussi de grands chanteurs comme Villalta, Gallardo el de Mor\u00f3n, Fernando el Herrero, Don Antonio Chac\u00f3n, Antonio RENGEL et Antonio Silva \u00ab\u00a0El Portugu\u00e9s\u00a0\u00bb. <\/span><\/p>\n<h2><b>Caract\u00e9ristiques des serranas<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Parmi les caract\u00e9ristiques qui permettent d&rsquo;identifier au mieux les <\/span><b>serranas<\/b><span style=\"font-weight: 400;\"> sont les suivantes :<\/span><\/p>\n<h3><b>Boussole<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Le m\u00e8tre des serranas <strong>est le m\u00eame que celui des seguiriyas<\/strong>, ce qui nous am\u00e8ne \u00e0 penser que, vu l&rsquo;anciennet\u00e9 des serranas, les <strong>seguiriya<\/strong> ont probablement <strong>adopt\u00e9 l&rsquo;air rythmique des serranas<\/strong> et non l&rsquo;inverse.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Bien que les deux styles soient tr\u00e8s similaires, la serrana a tendance \u00e0 jouer \u00e0 un tempo plus calme que les seguiriyas. Mais on peut aussi consid\u00e9rer que les premi\u00e8res livianas et serranas \u00e9taient jou\u00e9es sur un comp\u00e1s abandolao, comme les fandangos de la partie orientale de l&rsquo;Andalousie, et qu&rsquo;elles ont fini par adopter le style des seguiriyas afin d&rsquo;obtenir une <strong>plus grande profondeur flamenco.<\/strong> <\/span><\/p>\n<h3><b>Lettres<\/b><\/h3>\n<p><span style=\"font-weight: 400;\"><strong>Les couplets sont des seguidillas<\/strong> et, principalement la liviana, sont chant\u00e9s sur un couplet complet de la m\u00eame mani\u00e8re, compos\u00e9 de <strong>quatre vers pairs<\/strong>, le premier et le troisi\u00e8me de sept syllabes, le deuxi\u00e8me et le quatri\u00e8me de cinq syllabes. \u00c0 cela s&rsquo;ajoute un tercet (macho) compos\u00e9 de vers impairs de cinq syllabes et d&rsquo;un second de sept syllabes. La <strong>m\u00e9trique est la m\u00eame que celle des seguidillas castillanes<\/strong>.    <\/span><\/p>\n<h3><b>Ombre<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Comme le reste des seguiriyas, <strong>les serranas adoptent le mode flamenco<\/strong> et sont accompagn\u00e9es dans la tonalit\u00e9 de mi (por arriba), ce qui les distingue du reste des seguiriyas, qui sont g\u00e9n\u00e9ralement accompagn\u00e9es dans la tonalit\u00e9 de la (por medio).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En r\u00e9sum\u00e9, <strong>la serrana est une sorte de ca\u00f1a-polo qui adopte le m\u00e8tre de la seguiriya<\/strong>. Il s&rsquo;agit d&rsquo;un cante au ton lyrique et \u00e0 la large palette sonore, qui a \u00e9t\u00e9 flamencis\u00e9 au milieu du XIXe si\u00e8cle et qui est consid\u00e9r\u00e9 comme un des instruments les plus importants de la musique flamenca.   <\/span><b>le palo (forme) le plus illustratif de la naissance du flamenco<\/b><span style=\"font-weight: 400;\">. Une chanson courageuse, puissante et profonde, avec beaucoup de passion et de d\u00e9termination, exceptionnellement accrocheuse et m\u00e9lodieuse.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les serranas del flamenco sont un type de cante \u00e0 l&rsquo;atmosph\u00e8re paysanne, dont les th\u00e8mes font principalement r\u00e9f\u00e9rence \u00e0 la sierra, les protagonistes \u00e9tant des bergers, des contrebandiers, des bandits et des muletiers. D&rsquo;o\u00f9 son nom, qui fait r\u00e9f\u00e9rence \u00e0 la sierra andalouse, et plus pr\u00e9cis\u00e9ment \u00e0 la Serran\u00eda de Ronda. Un cante qui, au [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":6366,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[181],"tags":[],"class_list":["post-9283","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sans-categorie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Serranas : Quel est ce chant flamenco ? | Flamenco Alegr\u00eda<\/title>\n<meta name=\"description\" content=\"Les serranas flamencas sont un type de cante \u00e0 l&#039;atmosph\u00e8re paysanne issu de la seran\u00eda de ronda. Pour en savoir plus, consultez le site Flamenco Alegr\u00eda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/flamencomalaga.com\/fr\/blog\/serranas-quelle-est-cette-chanson-flamenco\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Serranas : Quel est ce chant flamenco ? | Flamenco Alegr\u00eda\" \/>\n<meta property=\"og:description\" content=\"Les serranas flamencas sont un type de cante \u00e0 l&#039;atmosph\u00e8re paysanne issu de la seran\u00eda de ronda. Pour en savoir plus, consultez le site Flamenco Alegr\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/flamencomalaga.com\/fr\/blog\/serranas-quelle-est-cette-chanson-flamenco\/\" \/>\n<meta property=\"og:site_name\" content=\"Flamenco Alegr\u00eda\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/alegriaflamencomalaga\/?locale=es_ES\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-04T09:52:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-26T14:58:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/flamencomalaga.com\/wp-content\/uploads\/2023\/04\/serranas-del-flamenco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jacinto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"jacinto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Serranas : Quel est ce chant flamenco ? | Flamenco Alegr\u00eda","description":"Les serranas flamencas sont un type de cante \u00e0 l'atmosph\u00e8re paysanne issu de la seran\u00eda de ronda. Pour en savoir plus, consultez le site Flamenco Alegr\u00eda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/flamencomalaga.com\/fr\/blog\/serranas-quelle-est-cette-chanson-flamenco\/","og_locale":"fr_FR","og_type":"article","og_title":"Serranas : Quel est ce chant flamenco ? | Flamenco Alegr\u00eda","og_description":"Les serranas flamencas sont un type de cante \u00e0 l'atmosph\u00e8re paysanne issu de la seran\u00eda de ronda. Pour en savoir plus, consultez le site Flamenco Alegr\u00eda.","og_url":"https:\/\/flamencomalaga.com\/fr\/blog\/serranas-quelle-est-cette-chanson-flamenco\/","og_site_name":"Flamenco Alegr\u00eda","article_publisher":"https:\/\/www.facebook.com\/alegriaflamencomalaga\/?locale=es_ES","article_published_time":"2023-05-04T09:52:23+00:00","article_modified_time":"2025-06-26T14:58:10+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/flamencomalaga.com\/wp-content\/uploads\/2023\/04\/serranas-del-flamenco.jpg","type":"image\/jpeg"}],"author":"jacinto","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"jacinto","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/flamencomalaga.com\/fr\/blog\/serranas-quelle-est-cette-chanson-flamenco\/#article","isPartOf":{"@id":"https:\/\/flamencomalaga.com\/fr\/blog\/serranas-quelle-est-cette-chanson-flamenco\/"},"author":{"name":"jacinto","@id":"https:\/\/flamencomalaga.com\/fr\/#\/schema\/person\/f24ed06767c15d0a72ee06a7e3c01fc8"},"headline":"Serranas : Quelle est cette chanson flamenco ?","datePublished":"2023-05-04T09:52:23+00:00","dateModified":"2025-06-26T14:58:10+00:00","mainEntityOfPage":{"@id":"https:\/\/flamencomalaga.com\/fr\/blog\/serranas-quelle-est-cette-chanson-flamenco\/"},"wordCount":838,"publisher":{"@id":"https:\/\/flamencomalaga.com\/fr\/#organization"},"image":{"@id":"https:\/\/flamencomalaga.com\/fr\/blog\/serranas-quelle-est-cette-chanson-flamenco\/#primaryimage"},"thumbnailUrl":"https:\/\/flamencomalaga.com\/wp-content\/uploads\/2023\/04\/serranas-del-flamenco.jpg?wsr","articleSection":["Sans cat\u00e9gorie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/flamencomalaga.com\/fr\/blog\/serranas-quelle-est-cette-chanson-flamenco\/","url":"https:\/\/flamencomalaga.com\/fr\/blog\/serranas-quelle-est-cette-chanson-flamenco\/","name":"Serranas : Quel est ce chant flamenco ? | Flamenco Alegr\u00eda","isPartOf":{"@id":"https:\/\/flamencomalaga.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/flamencomalaga.com\/fr\/blog\/serranas-quelle-est-cette-chanson-flamenco\/#primaryimage"},"image":{"@id":"https:\/\/flamencomalaga.com\/fr\/blog\/serranas-quelle-est-cette-chanson-flamenco\/#primaryimage"},"thumbnailUrl":"https:\/\/flamencomalaga.com\/wp-content\/uploads\/2023\/04\/serranas-del-flamenco.jpg?wsr","datePublished":"2023-05-04T09:52:23+00:00","dateModified":"2025-06-26T14:58:10+00:00","description":"Les serranas flamencas sont un type de cante \u00e0 l'atmosph\u00e8re paysanne issu de la seran\u00eda de ronda. Pour en savoir plus, consultez le site Flamenco Alegr\u00eda.","breadcrumb":{"@id":"https:\/\/flamencomalaga.com\/fr\/blog\/serranas-quelle-est-cette-chanson-flamenco\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/flamencomalaga.com\/fr\/blog\/serranas-quelle-est-cette-chanson-flamenco\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/flamencomalaga.com\/fr\/blog\/serranas-quelle-est-cette-chanson-flamenco\/#primaryimage","url":"https:\/\/flamencomalaga.com\/wp-content\/uploads\/2023\/04\/serranas-del-flamenco.jpg?wsr","contentUrl":"https:\/\/flamencomalaga.com\/wp-content\/uploads\/2023\/04\/serranas-del-flamenco.jpg?wsr","width":1000,"height":667,"caption":"sevillana bailando con palmeras de fondo"},{"@type":"BreadcrumbList","@id":"https:\/\/flamencomalaga.com\/fr\/blog\/serranas-quelle-est-cette-chanson-flamenco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/flamencomalaga.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Serranas : Quelle est cette chanson flamenco ?"}]},{"@type":"WebSite","@id":"https:\/\/flamencomalaga.com\/fr\/#website","url":"https:\/\/flamencomalaga.com\/fr\/","name":"Flamenco Alegr\u00eda y Gastronomia","description":"","publisher":{"@id":"https:\/\/flamencomalaga.com\/fr\/#organization"},"alternateName":"Flamenco Alegr\u00eda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/flamencomalaga.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/flamencomalaga.com\/fr\/#organization","name":"Flamenco Alegr\u00eda","alternateName":"Alegr\u00eda - Flamenco y Gastronom\u00eda","url":"https:\/\/flamencomalaga.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/flamencomalaga.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/flamencomalaga.com\/wp-content\/uploads\/2024\/07\/flamenco-malaga_logo.png?wsr","contentUrl":"https:\/\/flamencomalaga.com\/wp-content\/uploads\/2024\/07\/flamenco-malaga_logo.png?wsr","width":166,"height":85,"caption":"Flamenco Alegr\u00eda"},"image":{"@id":"https:\/\/flamencomalaga.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/alegriaflamencomalaga\/?locale=es_ES","https:\/\/www.instagram.com\/flamencomalagaalegria","https:\/\/www.tiktok.com\/@flamencomalaga"]},{"@type":"Person","@id":"https:\/\/flamencomalaga.com\/fr\/#\/schema\/person\/f24ed06767c15d0a72ee06a7e3c01fc8","name":"jacinto","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/be9e27bc927e6bdef9e9f8e2560ad975ebc1a341b34619fc9295577418cb58cb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/be9e27bc927e6bdef9e9f8e2560ad975ebc1a341b34619fc9295577418cb58cb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/be9e27bc927e6bdef9e9f8e2560ad975ebc1a341b34619fc9295577418cb58cb?s=96&d=mm&r=g","caption":"jacinto"},"url":"https:\/\/flamencomalaga.com\/fr\/blog\/author\/jacinto\/"}]}},"_links":{"self":[{"href":"https:\/\/flamencomalaga.com\/fr\/wp-json\/wp\/v2\/posts\/9283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flamencomalaga.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/flamencomalaga.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/flamencomalaga.com\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/flamencomalaga.com\/fr\/wp-json\/wp\/v2\/comments?post=9283"}],"version-history":[{"count":1,"href":"https:\/\/flamencomalaga.com\/fr\/wp-json\/wp\/v2\/posts\/9283\/revisions"}],"predecessor-version":[{"id":32112,"href":"https:\/\/flamencomalaga.com\/fr\/wp-json\/wp\/v2\/posts\/9283\/revisions\/32112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/flamencomalaga.com\/fr\/wp-json\/wp\/v2\/media\/6366"}],"wp:attachment":[{"href":"https:\/\/flamencomalaga.com\/fr\/wp-json\/wp\/v2\/media?parent=9283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/flamencomalaga.com\/fr\/wp-json\/wp\/v2\/categories?post=9283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/flamencomalaga.com\/fr\/wp-json\/wp\/v2\/tags?post=9283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}