{"id":16918,"date":"2024-01-30T09:00:28","date_gmt":"2024-01-30T08:00:28","guid":{"rendered":"https:\/\/flamencomalaga.com\/?p=16918"},"modified":"2024-09-10T15:19:39","modified_gmt":"2024-09-10T13:19:39","slug":"die-7-denkmaeler-in-malaga-die-sie-einmal-im-leben-oder-oefter-besuchen-sollten","status":"publish","type":"post","link":"https:\/\/flamencomalaga.com\/de\/blog\/die-7-denkmaeler-in-malaga-die-sie-einmal-im-leben-oder-oefter-besuchen-sollten\/","title":{"rendered":"Die 7 Denkm\u00e4ler in M\u00e1laga, die Sie einmal im Leben (oder \u00f6fter) besuchen sollten"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Sind Sie im<\/span> <a href=\"https:\/\/flamencomalaga.com\/blog\/turismo-malaga\/\"><span style=\"font-weight: 400;\">Tourismus in M\u00e1laga<\/span><\/a><span style=\"font-weight: 400;\"> und Sie wollen diese einzigartige Erfahrung in vollen Z\u00fcgen genie\u00dfen? Also, lesen Sie weiter, wir pr\u00e4sentieren Ihnen <\/span><b>die 7 Denkm\u00e4ler M\u00e1lagas, die Sie mindestens einmal im Leben besuchen sollten<\/b><span style=\"font-weight: 400;\">oder mehr, wenn Sie die M\u00f6glichkeit dazu haben. Die Emotionen, die Sie vor ihnen erleben werden, sind einfach unbeschreiblich!<\/span><\/p>\n<p><b>PS:<\/b> <span style=\"font-weight: 400;\">Wenn Sie in M\u00e1laga leben und noch keines dieser Monumente besucht haben, erleben Sie die Stadt nicht mit der Intensit\u00e4t, die sie verdient. Wir raten Ihnen daher, sie so bald wie m\u00f6glich zu besuchen, um Ihre Leidenschaft f\u00fcr diese magische Enklave zu erneuern.<\/span> <\/p>\n<h2><span style=\"font-weight: 400;\">Die 7 besten Denkm\u00e4ler M\u00e1lagas<\/span><\/h2>\n<h3><span style=\"font-weight: 400;\">1- R\u00f6misches Theater: <\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Wir beginnen unsere Liste der <\/span><b>Liste der Denkm\u00e4ler in M\u00e1laga<\/b><span style=\"font-weight: 400;\"> Das R\u00f6mische Theater wurde zum Kulturgut von besonderem Interesse erkl\u00e4rt. Sie liegt direkt am Fu\u00dfe der Alcazaba und war das wichtigste Symbol des r\u00f6mischen Hispaniens, daher ihre gro\u00dfe Bedeutung. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Au\u00dferdem befindet sich daneben ein modernes Interpretationszentrum, <\/span><b>Daneben befindet sich auch ein modernes Interpretationszentrum.<\/b><span style=\"font-weight: 400;\">Das Museum verf\u00fcgt \u00fcber ein ausgekl\u00fcgeltes technisches System, das es dem Besucher erm\u00f6glicht, sich \u00fcber die Br\u00e4uche der damaligen Zeit zu informieren. Als ob dies nicht schon genug w\u00e4re, hat sie auch noch <\/span><b>Shows werden im Inneren angeboten<\/b><span style=\"font-weight: 400;\">. Sonst noch jemand? <\/span><\/p>\n<h3><span style=\"font-weight: 400;\">2- Die Kathedrale von M\u00e1laga: <\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Obwohl die Kathedrale von M\u00e1laga im Volksmund als &#8222;La Manquita&#8220; bekannt ist, wird sie auch als &#8222;La Manquita&#8220; bezeichnet.<\/span><b><i>La Manquita<\/i><\/b><span style=\"font-weight: 400;\">&#8222;ihr vollst\u00e4ndiger Name ist &#8222;<\/span><i><span style=\"font-weight: 400;\">Santa Iglesia Catedral Bas\u00edlica de la Encarnaci\u00f3n &#8222;.<\/span><\/i><span style=\"font-weight: 400;\">&#8222;<\/span><i><span style=\"font-weight: 400;\">,<\/span><\/i><span style=\"font-weight: 400;\"> und ist m\u00f6glicherweise <\/span><b>das wichtigste Monument Malagas<\/b><span style=\"font-weight: 400;\"> -ein Muss-sehen. <\/span> <\/p>\n<p><span style=\"font-weight: 400;\">Ein Teil seiner Bedeutung liegt in der Tatsache, dass es auch eines der wertvollsten Renaissance-Monumente in Andalusien und Spanien ist. <\/span><b>eines der wertvollsten Renaissance-Bauwerke Andalusiens und ganz Spaniens.<\/b><span style=\"font-weight: 400;\">Sie befindet sich auch gegen\u00fcber der Plaza del Obispo, einem weiteren sch\u00f6nen Platz in M\u00e1laga, den man unbedingt sehen sollte. Ihr h\u00f6chster Turm ist 87 Meter hoch, und die Kathedrale stammt aus dem Jahr 1487 und kann nur mit einem Wort beschrieben werden: <\/span><b>BEEINDRUCKEND<\/b><span style=\"font-weight: 400;\">. <\/span> <\/p>\n<h3><span style=\"font-weight: 400;\">3- Picassos Geburtshaus<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Das Geburtshaus Picassos ist<\/span> <b>nicht nur eines der ber\u00fchmtesten Denkm\u00e4ler M\u00e1lagas,<\/b> <span style=\"font-weight: 400;\">sondern auch ein wichtiger Anlaufpunkt f\u00fcr K\u00fcnstler aus der ganzen Welt,<\/span> <b>die die kreative Atmosph\u00e4re <\/b><span style=\"font-weight: 400;\">im Inneren genie\u00dfen.<\/span> <\/p>\n<p><span style=\"font-weight: 400;\">Es befindet sich im Herzen der Stadt, neben der Plaza de la Merced (auf der sich das Malaga-Denkmal befindet, das wir weiter unten sehen werden). In Picassos Geburtshaus <\/span><b>k\u00f6nnen Sie einige seiner Werke besichtigen<\/b><span style=\"font-weight: 400;\">sowie seine Erlebnisse entdecken und verschiedene Ausstellungen und Veranstaltungen besuchen. <\/span> <\/p>\n<h3><span style=\"font-weight: 400;\">4- Denkmal f\u00fcr Torrijos<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Das Torrijos-Denkmal befindet sich auf der Plaza de la Merced, so dass es sich anbietet, es vor oder nach dem Besuch des Hauses von Picasso zu besichtigen. Dieses Denkmal in M\u00e1laga ist das bedeutendste des 19. Jahrhunderts, da es 1842 eingeweiht wurde. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es hei\u00dft so, weil es die Stelle ist <\/span><b>die genaue Stelle, an der General Torrijos begraben wurde.<\/b><span style=\"font-weight: 400;\"> und seine 48 Gef\u00e4hrten 1831 erschossen, als sie versuchten, den liberalen Aufstand zu f\u00f6rdern. Es ist ein historischer Ort, den man in M\u00e1laga besichtigen kann, auch wenn es etwas ist, das jeder sehr genie\u00dfen kann, <\/span><b>wird besonders Geschichtsinteressierten gefallen<\/b><span style=\"font-weight: 400;\">. <\/span> <\/p>\n<h3><span style=\"font-weight: 400;\">5- Schloss Gibralfaro<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Die Burg Gibralfaro ist eigentlich<\/span> <b>eine muslimische Festung<\/b>, <span style=\"font-weight: 400;\">die einst einen gro\u00dfen Leuchtturm besa\u00df, daher ihr Name.<\/span> <\/p>\n<p><b>Sie ist mit der Alcazaba von M\u00e1laga verbunden<\/b><span style=\"font-weight: 400;\"> (eine weitere der <\/span><a href=\"https:\/\/flamencomalaga.com\/blog\/sitios-ver-malaga\/\"><span style=\"font-weight: 400;\">der besten Sehensw\u00fcrdigkeiten M\u00e1lagas<\/span><\/a><span style=\"font-weight: 400;\">), so dass beide Denkm\u00e4ler gleichzeitig besichtigt werden k\u00f6nnen. Die Kreuzung wird durch sch\u00f6ne W\u00e4lle gebildet, die die H\u00fcgel hinunterlaufen und sehr sch\u00f6n anzusehen sind. Es befindet sich an einem hochgelegenen und privilegierten Ort, von dem aus es m\u00f6glich ist <\/span><b>Sie k\u00f6nnen die ganze Bucht von Malaga sehen (unserer Meinung nach eine der besten Aussichten<\/b><span style=\"font-weight: 400;\"> (unserer Meinung nach eine der besten Aussichten auf die ganze Stadt). <\/span> <\/p>\n<h3><span style=\"font-weight: 400;\">6- Friedhof von San Miguel<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Der Friedhof von San Miguel gilt als einer der bedeutendsten<\/span> <b>historisch-monumentalen Friedh\u00f6fe Spaniens<\/b> <span style=\"font-weight: 400;\">und ist eine der wenigen Nekropolen aus dem neunzehnten Jahrhundert, die heute noch intakt sind<\/span>. <\/p>\n<p><span style=\"font-weight: 400;\">Es ist ein weiterer Ort, der von Sch\u00f6nheits- und Geschichtsliebhabern gleicherma\u00dfen gesch\u00e4tzt wird, d<\/span><b>a die Fassade, die Kapelle, die Pantheons und die Kondolenzr\u00e4ume seit ihrer Errichtung zwischen dem Ende des 19<\/b><span style=\"font-weight: 400;\">. und dem Beginn des 20. Jahrhunderts intakt geblieben sind.<\/span> <\/p>\n<h3><span style=\"font-weight: 400;\">7- Denkmal f\u00fcr den Marquis von Larios: <\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Dieses in der Alameda Principal gelegene Denkmal von M\u00e1laga wurde im 19. Jahrhundert errichtet und ist dem genialen Manuel Domingo Larios y Larios (zweiter Marquis von Larios) gewidmet, der einen Gro\u00dfteil seines Lebens dem st\u00e4dtischen und sozialen Schutz von M\u00e1laga widmete. <\/span><\/p>\n<p><b>Es handelt sich um eine gro\u00dfe Statue aus dem Jahr 1899.<\/b><span style=\"font-weight: 400;\">aus Bronze auf einem kostbaren Marmorsockel. Wir wollen Ihnen keine weiteren Details verraten, damit Sie seine Sch\u00f6nheit und die starken Emotionen, die er vermittelt, in erster Person entdecken k\u00f6nnen. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Da Sie nun wissen <\/span><b>die 7 ber\u00fchmtesten Denkm\u00e4ler M\u00e1lagas<\/b><span style=\"font-weight: 400;\">m\u00f6chten wir das i-T\u00fcpfelchen empfehlen. Wenn Sie nach M\u00e1laga reisen und die Kultur dieser Stadt wirklich erleben m\u00f6chten, empfehlen wir Ihnen, dass Sie <\/span><a href=\"https:\/\/flamencomalaga.com\/espectaculos\/\"><b>eine Flamenco-Show sehen<\/b><\/a><span style=\"font-weight: 400;\">Bei Alegr\u00eda, Flamenco y Gastronom\u00eda finden Sie das Beste. <\/span><b>Besuchen Sie uns in der C. V\u00e9lez M\u00e1laga, 6, M\u00e1laga-Este.<\/b><span style=\"font-weight: 400;\">. <\/span> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sind Sie im Tourismus in M\u00e1laga und Sie wollen diese einzigartige Erfahrung in vollen Z\u00fcgen genie\u00dfen? Also, lesen Sie weiter, wir pr\u00e4sentieren Ihnen die 7 Denkm\u00e4ler M\u00e1lagas, die Sie mindestens einmal im Leben besuchen solltenoder mehr, wenn Sie die M\u00f6glichkeit dazu haben. Die Emotionen, die Sie vor ihnen erleben werden, sind einfach unbeschreiblich! PS: Wenn [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":16886,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-16918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>7 Denkm\u00e4ler in Malaga, die Sie besuchen sollten | Flamenco Malaga<\/title>\n<meta name=\"description\" content=\"Entdecken Sie die 7 emblematischsten Denkm\u00e4ler M\u00e1lagas, magische Orte, die Ihre Reise in eine unbeschreibliche Dimension f\u00fchren. Lesen Sie weiter!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/flamencomalaga.com\/de\/blog\/die-7-denkmaeler-in-malaga-die-sie-einmal-im-leben-oder-oefter-besuchen-sollten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7 Denkm\u00e4ler in Malaga, die Sie besuchen sollten | Flamenco Malaga\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie die 7 emblematischsten Denkm\u00e4ler M\u00e1lagas, magische Orte, die Ihre Reise in eine unbeschreibliche Dimension f\u00fchren. Lesen Sie weiter!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/flamencomalaga.com\/de\/blog\/die-7-denkmaeler-in-malaga-die-sie-einmal-im-leben-oder-oefter-besuchen-sollten\/\" \/>\n<meta property=\"og:site_name\" content=\"Flamenco Alegr\u00eda\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/alegriaflamencomalaga\/?locale=es_ES\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-30T08:00:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-10T13:19:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/flamencomalaga.com\/wp-content\/uploads\/2024\/01\/monumentos-de-malaga-mas-famosos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jacinto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"jacinto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"7 Denkm\u00e4ler in Malaga, die Sie besuchen sollten | Flamenco Malaga","description":"Entdecken Sie die 7 emblematischsten Denkm\u00e4ler M\u00e1lagas, magische Orte, die Ihre Reise in eine unbeschreibliche Dimension f\u00fchren. Lesen Sie weiter!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/flamencomalaga.com\/de\/blog\/die-7-denkmaeler-in-malaga-die-sie-einmal-im-leben-oder-oefter-besuchen-sollten\/","og_locale":"de_DE","og_type":"article","og_title":"7 Denkm\u00e4ler in Malaga, die Sie besuchen sollten | Flamenco Malaga","og_description":"Entdecken Sie die 7 emblematischsten Denkm\u00e4ler M\u00e1lagas, magische Orte, die Ihre Reise in eine unbeschreibliche Dimension f\u00fchren. Lesen Sie weiter!","og_url":"https:\/\/flamencomalaga.com\/de\/blog\/die-7-denkmaeler-in-malaga-die-sie-einmal-im-leben-oder-oefter-besuchen-sollten\/","og_site_name":"Flamenco Alegr\u00eda","article_publisher":"https:\/\/www.facebook.com\/alegriaflamencomalaga\/?locale=es_ES","article_published_time":"2024-01-30T08:00:28+00:00","article_modified_time":"2024-09-10T13:19:39+00:00","og_image":[{"width":1080,"height":340,"url":"https:\/\/flamencomalaga.com\/wp-content\/uploads\/2024\/01\/monumentos-de-malaga-mas-famosos.jpg","type":"image\/jpeg"}],"author":"jacinto","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"jacinto","Gesch\u00e4tzte Lesezeit":"4\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/flamencomalaga.com\/de\/blog\/die-7-denkmaeler-in-malaga-die-sie-einmal-im-leben-oder-oefter-besuchen-sollten\/#article","isPartOf":{"@id":"https:\/\/flamencomalaga.com\/de\/blog\/die-7-denkmaeler-in-malaga-die-sie-einmal-im-leben-oder-oefter-besuchen-sollten\/"},"author":{"name":"jacinto","@id":"https:\/\/flamencomalaga.com\/de\/#\/schema\/person\/f24ed06767c15d0a72ee06a7e3c01fc8"},"headline":"Die 7 Denkm\u00e4ler in M\u00e1laga, die Sie einmal im Leben (oder \u00f6fter) besuchen sollten","datePublished":"2024-01-30T08:00:28+00:00","dateModified":"2024-09-10T13:19:39+00:00","mainEntityOfPage":{"@id":"https:\/\/flamencomalaga.com\/de\/blog\/die-7-denkmaeler-in-malaga-die-sie-einmal-im-leben-oder-oefter-besuchen-sollten\/"},"wordCount":902,"publisher":{"@id":"https:\/\/flamencomalaga.com\/de\/#organization"},"image":{"@id":"https:\/\/flamencomalaga.com\/de\/blog\/die-7-denkmaeler-in-malaga-die-sie-einmal-im-leben-oder-oefter-besuchen-sollten\/#primaryimage"},"thumbnailUrl":"https:\/\/flamencomalaga.com\/wp-content\/uploads\/2024\/01\/monumentos-de-malaga-mas-famosos.jpg?wsr","articleSection":["Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/flamencomalaga.com\/de\/blog\/die-7-denkmaeler-in-malaga-die-sie-einmal-im-leben-oder-oefter-besuchen-sollten\/","url":"https:\/\/flamencomalaga.com\/de\/blog\/die-7-denkmaeler-in-malaga-die-sie-einmal-im-leben-oder-oefter-besuchen-sollten\/","name":"7 Denkm\u00e4ler in Malaga, die Sie besuchen sollten | Flamenco Malaga","isPartOf":{"@id":"https:\/\/flamencomalaga.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/flamencomalaga.com\/de\/blog\/die-7-denkmaeler-in-malaga-die-sie-einmal-im-leben-oder-oefter-besuchen-sollten\/#primaryimage"},"image":{"@id":"https:\/\/flamencomalaga.com\/de\/blog\/die-7-denkmaeler-in-malaga-die-sie-einmal-im-leben-oder-oefter-besuchen-sollten\/#primaryimage"},"thumbnailUrl":"https:\/\/flamencomalaga.com\/wp-content\/uploads\/2024\/01\/monumentos-de-malaga-mas-famosos.jpg?wsr","datePublished":"2024-01-30T08:00:28+00:00","dateModified":"2024-09-10T13:19:39+00:00","description":"Entdecken Sie die 7 emblematischsten Denkm\u00e4ler M\u00e1lagas, magische Orte, die Ihre Reise in eine unbeschreibliche Dimension f\u00fchren. Lesen Sie weiter!","breadcrumb":{"@id":"https:\/\/flamencomalaga.com\/de\/blog\/die-7-denkmaeler-in-malaga-die-sie-einmal-im-leben-oder-oefter-besuchen-sollten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/flamencomalaga.com\/de\/blog\/die-7-denkmaeler-in-malaga-die-sie-einmal-im-leben-oder-oefter-besuchen-sollten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/flamencomalaga.com\/de\/blog\/die-7-denkmaeler-in-malaga-die-sie-einmal-im-leben-oder-oefter-besuchen-sollten\/#primaryimage","url":"https:\/\/flamencomalaga.com\/wp-content\/uploads\/2024\/01\/monumentos-de-malaga-mas-famosos.jpg?wsr","contentUrl":"https:\/\/flamencomalaga.com\/wp-content\/uploads\/2024\/01\/monumentos-de-malaga-mas-famosos.jpg?wsr","width":1080,"height":340,"caption":"monumentos-de-malaga-mas-famosos"},{"@type":"BreadcrumbList","@id":"https:\/\/flamencomalaga.com\/de\/blog\/die-7-denkmaeler-in-malaga-die-sie-einmal-im-leben-oder-oefter-besuchen-sollten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/flamencomalaga.com\/de\/"},{"@type":"ListItem","position":2,"name":"Die 7 Denkm\u00e4ler in M\u00e1laga, die Sie einmal im Leben (oder \u00f6fter) besuchen sollten"}]},{"@type":"WebSite","@id":"https:\/\/flamencomalaga.com\/de\/#website","url":"https:\/\/flamencomalaga.com\/de\/","name":"Flamenco Alegr\u00eda y Gastronomia","description":"","publisher":{"@id":"https:\/\/flamencomalaga.com\/de\/#organization"},"alternateName":"Flamenco Alegr\u00eda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/flamencomalaga.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/flamencomalaga.com\/de\/#organization","name":"Flamenco Alegr\u00eda","alternateName":"Alegr\u00eda - Flamenco y Gastronom\u00eda","url":"https:\/\/flamencomalaga.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/flamencomalaga.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/flamencomalaga.com\/wp-content\/uploads\/2024\/07\/flamenco-malaga_logo.png?wsr","contentUrl":"https:\/\/flamencomalaga.com\/wp-content\/uploads\/2024\/07\/flamenco-malaga_logo.png?wsr","width":166,"height":85,"caption":"Flamenco Alegr\u00eda"},"image":{"@id":"https:\/\/flamencomalaga.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/alegriaflamencomalaga\/?locale=es_ES","https:\/\/www.instagram.com\/flamencomalagaalegria","https:\/\/www.tiktok.com\/@flamencomalaga"]},{"@type":"Person","@id":"https:\/\/flamencomalaga.com\/de\/#\/schema\/person\/f24ed06767c15d0a72ee06a7e3c01fc8","name":"jacinto","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/be9e27bc927e6bdef9e9f8e2560ad975ebc1a341b34619fc9295577418cb58cb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/be9e27bc927e6bdef9e9f8e2560ad975ebc1a341b34619fc9295577418cb58cb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/be9e27bc927e6bdef9e9f8e2560ad975ebc1a341b34619fc9295577418cb58cb?s=96&d=mm&r=g","caption":"jacinto"},"url":"https:\/\/flamencomalaga.com\/de\/blog\/author\/jacinto\/"}]}},"_links":{"self":[{"href":"https:\/\/flamencomalaga.com\/de\/wp-json\/wp\/v2\/posts\/16918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flamencomalaga.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/flamencomalaga.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/flamencomalaga.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/flamencomalaga.com\/de\/wp-json\/wp\/v2\/comments?post=16918"}],"version-history":[{"count":0,"href":"https:\/\/flamencomalaga.com\/de\/wp-json\/wp\/v2\/posts\/16918\/revisions"}],"wp:attachment":[{"href":"https:\/\/flamencomalaga.com\/de\/wp-json\/wp\/v2\/media?parent=16918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/flamencomalaga.com\/de\/wp-json\/wp\/v2\/categories?post=16918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/flamencomalaga.com\/de\/wp-json\/wp\/v2\/tags?post=16918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}